{"id":164247,"date":"2025-12-15T09:27:04","date_gmt":"2025-12-15T09:27:04","guid":{"rendered":"https:\/\/www.croatia-property.net\/property\/wohnung-mit-privatem-pool-makarska\/"},"modified":"2025-12-15T10:05:32","modified_gmt":"2025-12-15T10:05:32","slug":"wohnung-mit-privatem-pool-makarska-3545","status":"publish","type":"property","link":"https:\/\/www.croatia-property.net\/de\/property\/wohnung-mit-privatem-pool-makarska-3545\/","title":{"rendered":"Wohnung mit privatem Pool Makarska"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">Eine exzellente, sehr ger\u00e4umige Wohnung mit privatem Pool Makarska steht in bester Lage zum Verkauf. Genauer gesagt: unterhalb der Hauptstra\u00dfe, nur wenige Gehminuten vom Wasser entfernt. Die Wohnung verf\u00fcgt \u00fcber 2 Schlafzimmer, 2 Badezimmer, eine geschlossene Loggia an der Nordseite eines der Schlafzimmer, eine Wohnk\u00fcche und ein Wohnzimmer. Vom Wohnzimmer aus gelangt man auf eine gro\u00dfe Terrasse mit dem bereits erw\u00e4hnten Pool. Die Terrasse ist hell und luftig und bietet dank der teilweisen Umz\u00e4unung dennoch Privatsph\u00e4re.<\/p>\n\n<p class=\"wp-block-paragraph\">Diese Wohnung mit privatem Pool <a href=\"https:\/\/www.croatia-property.net\/de\/property-city\/makarska-de\/\">Makarska<\/a> befindet sich in einem hervorragenden Zustand und ist nahezu neuwertig: sehr moderne und funktionale M\u00f6bel, teilweise ma\u00dfgefertigt, hochwertige Haushaltsger\u00e4te, erstklassige Schreinerarbeiten und Bodenbel\u00e4ge. Im Preis inbegriffen ist ein Au\u00dfenstellplatz. Die <a href=\"https:\/\/www.croatia-property.net\/de\/property-type\/wohnungen\/\">Immobilie<\/a> kann auf Raten erworben werden. Aufgrund der au\u00dfergew\u00f6hnlichen Lage und des perfekten Zustands der Wohnung und des Pools bietet sich hier eine sehr gute Vermietungsm\u00f6glichkeit. Die Eigentumsverh\u00e4ltnisse sind gekl\u00e4rt.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Eine exzellente, sehr ger\u00e4umige Wohnung mit privatem Pool Makarska steht in bester Lage zum Verkauf. Genauer gesagt: unterhalb der Hauptstra\u00dfe, nur wenige Gehminuten vom Wasser entfernt. Die Wohnung verf\u00fcgt \u00fcber 2 Schlafzimmer, 2 Badezimmer, eine geschlossene Loggia an der Nordseite eines der Schlafzimmer, eine Wohnk\u00fcche und ein Wohnzimmer. Vom Wohnzimmer aus gelangt man auf eine&#8230;<\/p>\n","protected":false},"author":6,"featured_media":164211,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","property-feature":[703,204,108,128,214,112,129],"property-type":[99],"property-city":[195],"property-status":[101],"class_list":["post-164247","property","type-property","status-publish","has-post-thumbnail","hentry","property-feature-direkt-am-meer-de","property-feature-loggia-de","property-feature-meeresnaehe-de","property-feature-moebliert-de","property-feature-parking-de-2","property-feature-pool-de","property-feature-terrasse-de","property-type-wohnungen","property-city-makarska-de","property-status-verkauf-de"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Wohnung mit privatem Pool Makarska<\/title>\n<meta name=\"description\" content=\"Eine exzellente, sehr ger\u00e4umige Wohnung mit privatem Pool Makarska steht in bester Lage zum Verkauf. Genauer gesagt...\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.croatia-property.net\/de\/property\/wohnung-mit-privatem-pool-makarska-3545\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Wohnung mit privatem Pool Makarska\" \/>\n<meta property=\"og:description\" content=\"Eine exzellente, sehr ger\u00e4umige Wohnung mit privatem Pool Makarska steht in bester Lage zum Verkauf. Genauer gesagt...\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.croatia-property.net\/de\/property\/wohnung-mit-privatem-pool-makarska-3545\/\" \/>\n<meta property=\"og:site_name\" content=\"Immobilien in Kroatien\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/croatia.property.net\" \/>\n<meta property=\"article:modified_time\" content=\"2025-12-15T10:05:32+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.croatia-property.net\/wp-content\/uploads\/2025\/12\/apartment-with-private-pool-makarska-1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1024\" \/>\n\t<meta property=\"og:image:height\" content=\"683\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.croatia-property.net\\\/de\\\/property\\\/wohnung-mit-privatem-pool-makarska-3545\\\/\",\"url\":\"https:\\\/\\\/www.croatia-property.net\\\/de\\\/property\\\/wohnung-mit-privatem-pool-makarska-3545\\\/\",\"name\":\"Wohnung mit privatem Pool Makarska\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.croatia-property.net\\\/de\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.croatia-property.net\\\/de\\\/property\\\/wohnung-mit-privatem-pool-makarska-3545\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.croatia-property.net\\\/de\\\/property\\\/wohnung-mit-privatem-pool-makarska-3545\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.croatia-property.net\\\/wp-content\\\/uploads\\\/2025\\\/12\\\/apartment-with-private-pool-makarska-1.jpg\",\"datePublished\":\"2025-12-15T09:27:04+00:00\",\"dateModified\":\"2025-12-15T10:05:32+00:00\",\"description\":\"Eine exzellente, sehr ger\u00e4umige Wohnung mit privatem Pool Makarska steht in bester Lage zum Verkauf. Genauer gesagt...\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.croatia-property.net\\\/de\\\/property\\\/wohnung-mit-privatem-pool-makarska-3545\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.croatia-property.net\\\/de\\\/property\\\/wohnung-mit-privatem-pool-makarska-3545\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/www.croatia-property.net\\\/de\\\/property\\\/wohnung-mit-privatem-pool-makarska-3545\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.croatia-property.net\\\/wp-content\\\/uploads\\\/2025\\\/12\\\/apartment-with-private-pool-makarska-1.jpg\",\"contentUrl\":\"https:\\\/\\\/www.croatia-property.net\\\/wp-content\\\/uploads\\\/2025\\\/12\\\/apartment-with-private-pool-makarska-1.jpg\",\"width\":1024,\"height\":683,\"caption\":\"apartment with private pool makarska - 3545 - photo (1)\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.croatia-property.net\\\/de\\\/property\\\/wohnung-mit-privatem-pool-makarska-3545\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.croatia-property.net\\\/de\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Properties\",\"item\":\"https:\\\/\\\/www.croatia-property.net\\\/de\\\/property\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Wohnung mit privatem Pool Makarska\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.croatia-property.net\\\/de\\\/#website\",\"url\":\"https:\\\/\\\/www.croatia-property.net\\\/de\\\/\",\"name\":\"Immobilien in Kroatien\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.croatia-property.net\\\/de\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.croatia-property.net\\\/de\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.croatia-property.net\\\/de\\\/#organization\",\"name\":\"Croatia Property\",\"url\":\"https:\\\/\\\/www.croatia-property.net\\\/de\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/www.croatia-property.net\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.croatia-property.net\\\/wp-content\\\/uploads\\\/2017\\\/10\\\/cp-logo-bijelo.png\",\"contentUrl\":\"https:\\\/\\\/www.croatia-property.net\\\/wp-content\\\/uploads\\\/2017\\\/10\\\/cp-logo-bijelo.png\",\"width\":1916,\"height\":953,\"caption\":\"Croatia Property\"},\"image\":{\"@id\":\"https:\\\/\\\/www.croatia-property.net\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/croatia.property.net\",\"https:\\\/\\\/www.instagram.com\\\/croatiaproperty\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Wohnung mit privatem Pool Makarska","description":"Eine exzellente, sehr ger\u00e4umige Wohnung mit privatem Pool Makarska steht in bester Lage zum Verkauf. Genauer gesagt...","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.croatia-property.net\/de\/property\/wohnung-mit-privatem-pool-makarska-3545\/","og_locale":"de_DE","og_type":"article","og_title":"Wohnung mit privatem Pool Makarska","og_description":"Eine exzellente, sehr ger\u00e4umige Wohnung mit privatem Pool Makarska steht in bester Lage zum Verkauf. Genauer gesagt...","og_url":"https:\/\/www.croatia-property.net\/de\/property\/wohnung-mit-privatem-pool-makarska-3545\/","og_site_name":"Immobilien in Kroatien","article_publisher":"https:\/\/www.facebook.com\/croatia.property.net","article_modified_time":"2025-12-15T10:05:32+00:00","og_image":[{"width":1024,"height":683,"url":"https:\/\/www.croatia-property.net\/wp-content\/uploads\/2025\/12\/apartment-with-private-pool-makarska-1.jpg","type":"image\/jpeg"}],"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.croatia-property.net\/de\/property\/wohnung-mit-privatem-pool-makarska-3545\/","url":"https:\/\/www.croatia-property.net\/de\/property\/wohnung-mit-privatem-pool-makarska-3545\/","name":"Wohnung mit privatem Pool Makarska","isPartOf":{"@id":"https:\/\/www.croatia-property.net\/de\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.croatia-property.net\/de\/property\/wohnung-mit-privatem-pool-makarska-3545\/#primaryimage"},"image":{"@id":"https:\/\/www.croatia-property.net\/de\/property\/wohnung-mit-privatem-pool-makarska-3545\/#primaryimage"},"thumbnailUrl":"https:\/\/www.croatia-property.net\/wp-content\/uploads\/2025\/12\/apartment-with-private-pool-makarska-1.jpg","datePublished":"2025-12-15T09:27:04+00:00","dateModified":"2025-12-15T10:05:32+00:00","description":"Eine exzellente, sehr ger\u00e4umige Wohnung mit privatem Pool Makarska steht in bester Lage zum Verkauf. Genauer gesagt...","breadcrumb":{"@id":"https:\/\/www.croatia-property.net\/de\/property\/wohnung-mit-privatem-pool-makarska-3545\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.croatia-property.net\/de\/property\/wohnung-mit-privatem-pool-makarska-3545\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.croatia-property.net\/de\/property\/wohnung-mit-privatem-pool-makarska-3545\/#primaryimage","url":"https:\/\/www.croatia-property.net\/wp-content\/uploads\/2025\/12\/apartment-with-private-pool-makarska-1.jpg","contentUrl":"https:\/\/www.croatia-property.net\/wp-content\/uploads\/2025\/12\/apartment-with-private-pool-makarska-1.jpg","width":1024,"height":683,"caption":"apartment with private pool makarska - 3545 - photo (1)"},{"@type":"BreadcrumbList","@id":"https:\/\/www.croatia-property.net\/de\/property\/wohnung-mit-privatem-pool-makarska-3545\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.croatia-property.net\/de\/"},{"@type":"ListItem","position":2,"name":"Properties","item":"https:\/\/www.croatia-property.net\/de\/property\/"},{"@type":"ListItem","position":3,"name":"Wohnung mit privatem Pool Makarska"}]},{"@type":"WebSite","@id":"https:\/\/www.croatia-property.net\/de\/#website","url":"https:\/\/www.croatia-property.net\/de\/","name":"Immobilien in Kroatien","description":"","publisher":{"@id":"https:\/\/www.croatia-property.net\/de\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.croatia-property.net\/de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/www.croatia-property.net\/de\/#organization","name":"Croatia Property","url":"https:\/\/www.croatia-property.net\/de\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.croatia-property.net\/de\/#\/schema\/logo\/image\/","url":"https:\/\/www.croatia-property.net\/wp-content\/uploads\/2017\/10\/cp-logo-bijelo.png","contentUrl":"https:\/\/www.croatia-property.net\/wp-content\/uploads\/2017\/10\/cp-logo-bijelo.png","width":1916,"height":953,"caption":"Croatia Property"},"image":{"@id":"https:\/\/www.croatia-property.net\/de\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/croatia.property.net","https:\/\/www.instagram.com\/croatiaproperty"]}]}},"property_meta":{"REAL_HOMES_property_price":"480000","REAL_HOMES_property_old_price":"","REAL_HOMES_property_price_prefix":"","REAL_HOMES_property_price_postfix":"","REAL_HOMES_property_size":"83,55","REAL_HOMES_property_size_postfix":"","REAL_HOMES_property_lot_size":"","REAL_HOMES_property_lot_size_postfix":"","REAL_HOMES_property_bedrooms":"2","REAL_HOMES_property_bathrooms":"2","REAL_HOMES_property_garage":"","REAL_HOMES_property_id":"3545","REAL_HOMES_property_year_built":"","rvr_property_owner":"","REAL_HOMES_featured":"0","REAL_HOMES_additional_details_list":[],"REAL_HOMES_property_location":{"latitude":"43.2939756","longitude":"17.020242","zoom":"14"},"REAL_HOMES_property_address":"Makarska, Grad Makarska, Splitsko-dalmatinska \u017eupanija, 21300, Hrvatska","REAL_HOMES_property_map":"0","REAL_HOMES_property_images":[{"width":150,"height":150,"file":"2025\/12\/apartment-with-private-pool-makarska-1.jpg","filesize":223935,"sizes":{"medium":{"file":"apartment-with-private-pool-makarska-1-300x200.jpg","width":300,"height":200,"mime-type":"image\/jpeg","filesize":15850,"url":"https:\/\/www.croatia-property.net\/wp-content\/uploads\/2025\/12\/apartment-with-private-pool-makarska-1-300x200.jpg"},"thumbnail":{"file":"apartment-with-private-pool-makarska-1-150x150.jpg","width":150,"height":150,"mime-type":"image\/jpeg","filesize":6660,"url":"https:\/\/www.croatia-property.net\/wp-content\/uploads\/2025\/12\/apartment-with-private-pool-makarska-1-150x150.jpg"},"medium_large":{"file":"apartment-with-private-pool-makarska-1-768x512.jpg","width":768,"height":512,"mime-type":"image\/jpeg","filesize":73906,"url":"https:\/\/www.croatia-property.net\/wp-content\/uploads\/2025\/12\/apartment-with-private-pool-makarska-1-768x512.jpg"},"post-thumbnail":{"file":"apartment-with-private-pool-makarska-1-150x100.jpg","width":150,"height":100,"mime-type":"image\/jpeg","filesize":5507,"url":"https:\/\/www.croatia-property.net\/wp-content\/uploads\/2025\/12\/apartment-with-private-pool-makarska-1-150x100.jpg"},"modern-property-child-slider":{"file":"apartment-with-private-pool-makarska-1-680x510.jpg","width":680,"height":510,"mime-type":"image\/jpeg","filesize":66260,"url":"https:\/\/www.croatia-property.net\/wp-content\/uploads\/2025\/12\/apartment-with-private-pool-makarska-1-680x510.jpg"},"property-thumb-image":{"file":"apartment-with-private-pool-makarska-1-488x326.jpg","width":488,"height":326,"mime-type":"image\/jpeg","filesize":35027,"url":"https:\/\/www.croatia-property.net\/wp-content\/uploads\/2025\/12\/apartment-with-private-pool-makarska-1-488x326.jpg"},"property-detail-video-image":{"file":"apartment-with-private-pool-makarska-1-818x417.jpg","width":818,"height":417,"mime-type":"image\/jpeg","filesize":69249,"url":"https:\/\/www.croatia-property.net\/wp-content\/uploads\/2025\/12\/apartment-with-private-pool-makarska-1-818x417.jpg"},"agent-image":{"file":"apartment-with-private-pool-makarska-1-210x210.jpg","width":210,"height":210,"mime-type":"image\/jpeg","filesize":11500,"url":"https:\/\/www.croatia-property.net\/wp-content\/uploads\/2025\/12\/apartment-with-private-pool-makarska-1-210x210.jpg"},"partners-logo":{"file":"apartment-with-private-pool-makarska-1-600x683.jpg","width":600,"height":683,"mime-type":"image\/jpeg","filesize":81755,"url":"https:\/\/www.croatia-property.net\/wp-content\/uploads\/2025\/12\/apartment-with-private-pool-makarska-1-600x683.jpg"},"gallery-two-column-image":{"file":"apartment-with-private-pool-makarska-1-536x269.jpg","width":536,"height":269,"mime-type":"image\/jpeg","filesize":33941,"url":"https:\/\/www.croatia-property.net\/wp-content\/uploads\/2025\/12\/apartment-with-private-pool-makarska-1-536x269.jpg"},"property-detail-slider-image-two":{"file":"apartment-with-private-pool-makarska-1-1024x648.jpg","width":1024,"height":648,"mime-type":"image\/jpeg","filesize":128632,"url":"https:\/\/www.croatia-property.net\/wp-content\/uploads\/2025\/12\/apartment-with-private-pool-makarska-1-1024x648.jpg"},"property-detail-slider-thumb":{"file":"apartment-with-private-pool-makarska-1-82x60.jpg","width":82,"height":60,"mime-type":"image\/jpeg","filesize":2555,"url":"https:\/\/www.croatia-property.net\/wp-content\/uploads\/2025\/12\/apartment-with-private-pool-makarska-1-82x60.jpg"}},"image_meta":{"aperture":"2.2","credit":"","camera":"Galaxy A54 5G","caption":"","created_timestamp":"1765445724","copyright":"","focal_length":"1.74","iso":"40","shutter_speed":"0.00042194092827004","title":"","orientation":"1","keywords":[]},"ID":"164213","name":"apartment-with-private-pool-makarska-1.jpg","path":"\/home\/gagwyweu\/public_html\/wp-content\/uploads\/2025\/12\/apartment-with-private-pool-makarska-1.jpg","url":"https:\/\/www.croatia-property.net\/wp-content\/uploads\/2025\/12\/apartment-with-private-pool-makarska-1-150x150.jpg","full_url":"https:\/\/www.croatia-property.net\/wp-content\/uploads\/2025\/12\/apartment-with-private-pool-makarska-1.jpg","title":"apartment with private pool makarska (1)","caption":"apartment with private pool makarska - 3545 - photo (1)","description":"","alt":"apartment with private pool makarska - 3545 (1)","srcset":"https:\/\/www.croatia-property.net\/wp-content\/uploads\/2025\/12\/apartment-with-private-pool-makarska-1-150x150.jpg 150w, https:\/\/www.croatia-property.net\/wp-content\/uploads\/2025\/12\/apartment-with-private-pool-makarska-1-210x210.jpg 210w"},{"width":150,"height":150,"file":"2025\/12\/apartment-with-private-pool-makarska-2.jpg","filesize":114648,"sizes":{"medium":{"file":"apartment-with-private-pool-makarska-2-300x200.jpg","width":300,"height":200,"mime-type":"image\/jpeg","filesize":11468,"url":"https:\/\/www.croatia-property.net\/wp-content\/uploads\/2025\/12\/apartment-with-private-pool-makarska-2-300x200.jpg"},"thumbnail":{"file":"apartment-with-private-pool-makarska-2-150x150.jpg","width":150,"height":150,"mime-type":"image\/jpeg","filesize":5177,"url":"https:\/\/www.croatia-property.net\/wp-content\/uploads\/2025\/12\/apartment-with-private-pool-makarska-2-150x150.jpg"},"medium_large":{"file":"apartment-with-private-pool-makarska-2-768x512.jpg","width":768,"height":512,"mime-type":"image\/jpeg","filesize":50735,"url":"https:\/\/www.croatia-property.net\/wp-content\/uploads\/2025\/12\/apartment-with-private-pool-makarska-2-768x512.jpg"},"post-thumbnail":{"file":"apartment-with-private-pool-makarska-2-150x100.jpg","width":150,"height":100,"mime-type":"image\/jpeg","filesize":4215,"url":"https:\/\/www.croatia-property.net\/wp-content\/uploads\/2025\/12\/apartment-with-private-pool-makarska-2-150x100.jpg"},"modern-property-child-slider":{"file":"apartment-with-private-pool-makarska-2-680x510.jpg","width":680,"height":510,"mime-type":"image\/jpeg","filesize":45806,"url":"https:\/\/www.croatia-property.net\/wp-content\/uploads\/2025\/12\/apartment-with-private-pool-makarska-2-680x510.jpg"},"property-thumb-image":{"file":"apartment-with-private-pool-makarska-2-488x326.jpg","width":488,"height":326,"mime-type":"image\/jpeg","filesize":24493,"url":"https:\/\/www.croatia-property.net\/wp-content\/uploads\/2025\/12\/apartment-with-private-pool-makarska-2-488x326.jpg"},"property-detail-video-image":{"file":"apartment-with-private-pool-makarska-2-818x417.jpg","width":818,"height":417,"mime-type":"image\/jpeg","filesize":47258,"url":"https:\/\/www.croatia-property.net\/wp-content\/uploads\/2025\/12\/apartment-with-private-pool-makarska-2-818x417.jpg"},"agent-image":{"file":"apartment-with-private-pool-makarska-2-210x210.jpg","width":210,"height":210,"mime-type":"image\/jpeg","filesize":8567,"url":"https:\/\/www.croatia-property.net\/wp-content\/uploads\/2025\/12\/apartment-with-private-pool-makarska-2-210x210.jpg"},"partners-logo":{"file":"apartment-with-private-pool-makarska-2-600x683.jpg","width":600,"height":683,"mime-type":"image\/jpeg","filesize":52464,"url":"https:\/\/www.croatia-property.net\/wp-content\/uploads\/2025\/12\/apartment-with-private-pool-makarska-2-600x683.jpg"},"gallery-two-column-image":{"file":"apartment-with-private-pool-makarska-2-536x269.jpg","width":536,"height":269,"mime-type":"image\/jpeg","filesize":23754,"url":"https:\/\/www.croatia-property.net\/wp-content\/uploads\/2025\/12\/apartment-with-private-pool-makarska-2-536x269.jpg"},"property-detail-slider-image-two":{"file":"apartment-with-private-pool-makarska-2-1024x648.jpg","width":1024,"height":648,"mime-type":"image\/jpeg","filesize":85472,"url":"https:\/\/www.croatia-property.net\/wp-content\/uploads\/2025\/12\/apartment-with-private-pool-makarska-2-1024x648.jpg"},"property-detail-slider-thumb":{"file":"apartment-with-private-pool-makarska-2-82x60.jpg","width":82,"height":60,"mime-type":"image\/jpeg","filesize":2159,"url":"https:\/\/www.croatia-property.net\/wp-content\/uploads\/2025\/12\/apartment-with-private-pool-makarska-2-82x60.jpg"}},"image_meta":{"aperture":"2.2","credit":"","camera":"Galaxy A54 5G","caption":"","created_timestamp":"1765445696","copyright":"","focal_length":"1.74","iso":"80","shutter_speed":"0.02","title":"","orientation":"1","keywords":[]},"ID":"164216","name":"apartment-with-private-pool-makarska-2.jpg","path":"\/home\/gagwyweu\/public_html\/wp-content\/uploads\/2025\/12\/apartment-with-private-pool-makarska-2.jpg","url":"https:\/\/www.croatia-property.net\/wp-content\/uploads\/2025\/12\/apartment-with-private-pool-makarska-2-150x150.jpg","full_url":"https:\/\/www.croatia-property.net\/wp-content\/uploads\/2025\/12\/apartment-with-private-pool-makarska-2.jpg","title":"apartment with private pool makarska (2)","caption":"apartment with private pool makarska - 3545 - photo (2)","description":"","alt":"apartment with private pool makarska - 3545 (2)","srcset":"https:\/\/www.croatia-property.net\/wp-content\/uploads\/2025\/12\/apartment-with-private-pool-makarska-2-150x150.jpg 150w, https:\/\/www.croatia-property.net\/wp-content\/uploads\/2025\/12\/apartment-with-private-pool-makarska-2-210x210.jpg 210w"},{"width":150,"height":150,"file":"2025\/12\/apartment-with-private-pool-makarska-3.jpg","filesize":103668,"sizes":{"medium":{"file":"apartment-with-private-pool-makarska-3-300x200.jpg","width":300,"height":200,"mime-type":"image\/jpeg","filesize":11238,"url":"https:\/\/www.croatia-property.net\/wp-content\/uploads\/2025\/12\/apartment-with-private-pool-makarska-3-300x200.jpg"},"thumbnail":{"file":"apartment-with-private-pool-makarska-3-150x150.jpg","width":150,"height":150,"mime-type":"image\/jpeg","filesize":5435,"url":"https:\/\/www.croatia-property.net\/wp-content\/uploads\/2025\/12\/apartment-with-private-pool-makarska-3-150x150.jpg"},"medium_large":{"file":"apartment-with-private-pool-makarska-3-768x512.jpg","width":768,"height":512,"mime-type":"image\/jpeg","filesize":46621,"url":"https:\/\/www.croatia-property.net\/wp-content\/uploads\/2025\/12\/apartment-with-private-pool-makarska-3-768x512.jpg"},"post-thumbnail":{"file":"apartment-with-private-pool-makarska-3-150x100.jpg","width":150,"height":100,"mime-type":"image\/jpeg","filesize":4380,"url":"https:\/\/www.croatia-property.net\/wp-content\/uploads\/2025\/12\/apartment-with-private-pool-makarska-3-150x100.jpg"},"modern-property-child-slider":{"file":"apartment-with-private-pool-makarska-3-680x510.jpg","width":680,"height":510,"mime-type":"image\/jpeg","filesize":42244,"url":"https:\/\/www.croatia-property.net\/wp-content\/uploads\/2025\/12\/apartment-with-private-pool-makarska-3-680x510.jpg"},"property-thumb-image":{"file":"apartment-with-private-pool-makarska-3-488x326.jpg","width":488,"height":326,"mime-type":"image\/jpeg","filesize":23265,"url":"https:\/\/www.croatia-property.net\/wp-content\/uploads\/2025\/12\/apartment-with-private-pool-makarska-3-488x326.jpg"},"property-detail-video-image":{"file":"apartment-with-private-pool-makarska-3-818x417.jpg","width":818,"height":417,"mime-type":"image\/jpeg","filesize":42235,"url":"https:\/\/www.croatia-property.net\/wp-content\/uploads\/2025\/12\/apartment-with-private-pool-makarska-3-818x417.jpg"},"agent-image":{"file":"apartment-with-private-pool-makarska-3-210x210.jpg","width":210,"height":210,"mime-type":"image\/jpeg","filesize":8859,"url":"https:\/\/www.croatia-property.net\/wp-content\/uploads\/2025\/12\/apartment-with-private-pool-makarska-3-210x210.jpg"},"partners-logo":{"file":"apartment-with-private-pool-makarska-3-600x683.jpg","width":600,"height":683,"mime-type":"image\/jpeg","filesize":54065,"url":"https:\/\/www.croatia-property.net\/wp-content\/uploads\/2025\/12\/apartment-with-private-pool-makarska-3-600x683.jpg"},"gallery-two-column-image":{"file":"apartment-with-private-pool-makarska-3-536x269.jpg","width":536,"height":269,"mime-type":"image\/jpeg","filesize":21396,"url":"https:\/\/www.croatia-property.net\/wp-content\/uploads\/2025\/12\/apartment-with-private-pool-makarska-3-536x269.jpg"},"property-detail-slider-image-two":{"file":"apartment-with-private-pool-makarska-3-1024x648.jpg","width":1024,"height":648,"mime-type":"image\/jpeg","filesize":77698,"url":"https:\/\/www.croatia-property.net\/wp-content\/uploads\/2025\/12\/apartment-with-private-pool-makarska-3-1024x648.jpg"},"property-detail-slider-thumb":{"file":"apartment-with-private-pool-makarska-3-82x60.jpg","width":82,"height":60,"mime-type":"image\/jpeg","filesize":2258,"url":"https:\/\/www.croatia-property.net\/wp-content\/uploads\/2025\/12\/apartment-with-private-pool-makarska-3-82x60.jpg"}},"image_meta":{"aperture":"2.2","credit":"","camera":"Galaxy A54 5G","caption":"","created_timestamp":"1765445832","copyright":"","focal_length":"1.74","iso":"125","shutter_speed":"0.02","title":"","orientation":"1","keywords":[]},"ID":"164219","name":"apartment-with-private-pool-makarska-3.jpg","path":"\/home\/gagwyweu\/public_html\/wp-content\/uploads\/2025\/12\/apartment-with-private-pool-makarska-3.jpg","url":"https:\/\/www.croatia-property.net\/wp-content\/uploads\/2025\/12\/apartment-with-private-pool-makarska-3-150x150.jpg","full_url":"https:\/\/www.croatia-property.net\/wp-content\/uploads\/2025\/12\/apartment-with-private-pool-makarska-3.jpg","title":"apartment with private pool makarska (3)","caption":"apartment with private pool makarska - 3545 - photo (3)","description":"","alt":"apartment with private pool makarska - 3545 (3)","srcset":"https:\/\/www.croatia-property.net\/wp-content\/uploads\/2025\/12\/apartment-with-private-pool-makarska-3-150x150.jpg 150w, https:\/\/www.croatia-property.net\/wp-content\/uploads\/2025\/12\/apartment-with-private-pool-makarska-3-210x210.jpg 210w"},{"width":150,"height":150,"file":"2025\/12\/apartment-with-private-pool-makarska-4.jpg","filesize":117591,"sizes":{"medium":{"file":"apartment-with-private-pool-makarska-4-300x200.jpg","width":300,"height":200,"mime-type":"image\/jpeg","filesize":9522,"url":"https:\/\/www.croatia-property.net\/wp-content\/uploads\/2025\/12\/apartment-with-private-pool-makarska-4-300x200.jpg"},"thumbnail":{"file":"apartment-with-private-pool-makarska-4-150x150.jpg","width":150,"height":150,"mime-type":"image\/jpeg","filesize":5135,"url":"https:\/\/www.croatia-property.net\/wp-content\/uploads\/2025\/12\/apartment-with-private-pool-makarska-4-150x150.jpg"},"medium_large":{"file":"apartment-with-private-pool-makarska-4-768x512.jpg","width":768,"height":512,"mime-type":"image\/jpeg","filesize":39682,"url":"https:\/\/www.croatia-property.net\/wp-content\/uploads\/2025\/12\/apartment-with-private-pool-makarska-4-768x512.jpg"},"post-thumbnail":{"file":"apartment-with-private-pool-makarska-4-150x100.jpg","width":150,"height":100,"mime-type":"image\/jpeg","filesize":3766,"url":"https:\/\/www.croatia-property.net\/wp-content\/uploads\/2025\/12\/apartment-with-private-pool-makarska-4-150x100.jpg"},"modern-property-child-slider":{"file":"apartment-with-private-pool-makarska-4-680x510.jpg","width":680,"height":510,"mime-type":"image\/jpeg","filesize":37309,"url":"https:\/\/www.croatia-property.net\/wp-content\/uploads\/2025\/12\/apartment-with-private-pool-makarska-4-680x510.jpg"},"property-thumb-image":{"file":"apartment-with-private-pool-makarska-4-488x326.jpg","width":488,"height":326,"mime-type":"image\/jpeg","filesize":19717,"url":"https:\/\/www.croatia-property.net\/wp-content\/uploads\/2025\/12\/apartment-with-private-pool-makarska-4-488x326.jpg"},"property-detail-video-image":{"file":"apartment-with-private-pool-makarska-4-818x417.jpg","width":818,"height":417,"mime-type":"image\/jpeg","filesize":36116,"url":"https:\/\/www.croatia-property.net\/wp-content\/uploads\/2025\/12\/apartment-with-private-pool-makarska-4-818x417.jpg"},"agent-image":{"file":"apartment-with-private-pool-makarska-4-210x210.jpg","width":210,"height":210,"mime-type":"image\/jpeg","filesize":8417,"url":"https:\/\/www.croatia-property.net\/wp-content\/uploads\/2025\/12\/apartment-with-private-pool-makarska-4-210x210.jpg"},"partners-logo":{"file":"apartment-with-private-pool-makarska-4-600x683.jpg","width":600,"height":683,"mime-type":"image\/jpeg","filesize":50001,"url":"https:\/\/www.croatia-property.net\/wp-content\/uploads\/2025\/12\/apartment-with-private-pool-makarska-4-600x683.jpg"},"gallery-two-column-image":{"file":"apartment-with-private-pool-makarska-4-536x269.jpg","width":536,"height":269,"mime-type":"image\/jpeg","filesize":18372,"url":"https:\/\/www.croatia-property.net\/wp-content\/uploads\/2025\/12\/apartment-with-private-pool-makarska-4-536x269.jpg"},"property-detail-slider-image-two":{"file":"apartment-with-private-pool-makarska-4-1024x648.jpg","width":1024,"height":648,"mime-type":"image\/jpeg","filesize":64162,"url":"https:\/\/www.croatia-property.net\/wp-content\/uploads\/2025\/12\/apartment-with-private-pool-makarska-4-1024x648.jpg"},"property-detail-slider-thumb":{"file":"apartment-with-private-pool-makarska-4-82x60.jpg","width":82,"height":60,"mime-type":"image\/jpeg","filesize":2053,"url":"https:\/\/www.croatia-property.net\/wp-content\/uploads\/2025\/12\/apartment-with-private-pool-makarska-4-82x60.jpg"}},"image_meta":{"aperture":"2.2","credit":"","camera":"Galaxy A54 5G","caption":"","created_timestamp":"1765445841","copyright":"","focal_length":"1.74","iso":"200","shutter_speed":"0.03030303030303","title":"","orientation":"1","keywords":[]},"ID":"164222","name":"apartment-with-private-pool-makarska-4.jpg","path":"\/home\/gagwyweu\/public_html\/wp-content\/uploads\/2025\/12\/apartment-with-private-pool-makarska-4.jpg","url":"https:\/\/www.croatia-property.net\/wp-content\/uploads\/2025\/12\/apartment-with-private-pool-makarska-4-150x150.jpg","full_url":"https:\/\/www.croatia-property.net\/wp-content\/uploads\/2025\/12\/apartment-with-private-pool-makarska-4.jpg","title":"apartment with private pool makarska (4)","caption":"apartment with private pool makarska - 3545 - photo (4)","description":"","alt":"apartment with private pool makarska - 3545 (4)","srcset":"https:\/\/www.croatia-property.net\/wp-content\/uploads\/2025\/12\/apartment-with-private-pool-makarska-4-150x150.jpg 150w, https:\/\/www.croatia-property.net\/wp-content\/uploads\/2025\/12\/apartment-with-private-pool-makarska-4-210x210.jpg 210w"},{"width":150,"height":150,"file":"2025\/12\/apartment-with-private-pool-makarska-5.jpg","filesize":145515,"sizes":{"medium":{"file":"apartment-with-private-pool-makarska-5-300x200.jpg","width":300,"height":200,"mime-type":"image\/jpeg","filesize":14267,"url":"https:\/\/www.croatia-property.net\/wp-content\/uploads\/2025\/12\/apartment-with-private-pool-makarska-5-300x200.jpg"},"thumbnail":{"file":"apartment-with-private-pool-makarska-5-150x150.jpg","width":150,"height":150,"mime-type":"image\/jpeg","filesize":6831,"url":"https:\/\/www.croatia-property.net\/wp-content\/uploads\/2025\/12\/apartment-with-private-pool-makarska-5-150x150.jpg"},"medium_large":{"file":"apartment-with-private-pool-makarska-5-768x512.jpg","width":768,"height":512,"mime-type":"image\/jpeg","filesize":63404,"url":"https:\/\/www.croatia-property.net\/wp-content\/uploads\/2025\/12\/apartment-with-private-pool-makarska-5-768x512.jpg"},"post-thumbnail":{"file":"apartment-with-private-pool-makarska-5-150x100.jpg","width":150,"height":100,"mime-type":"image\/jpeg","filesize":5333,"url":"https:\/\/www.croatia-property.net\/wp-content\/uploads\/2025\/12\/apartment-with-private-pool-makarska-5-150x100.jpg"},"modern-property-child-slider":{"file":"apartment-with-private-pool-makarska-5-680x510.jpg","width":680,"height":510,"mime-type":"image\/jpeg","filesize":58149,"url":"https:\/\/www.croatia-property.net\/wp-content\/uploads\/2025\/12\/apartment-with-private-pool-makarska-5-680x510.jpg"},"property-thumb-image":{"file":"apartment-with-private-pool-makarska-5-488x326.jpg","width":488,"height":326,"mime-type":"image\/jpeg","filesize":30491,"url":"https:\/\/www.croatia-property.net\/wp-content\/uploads\/2025\/12\/apartment-with-private-pool-makarska-5-488x326.jpg"},"property-detail-video-image":{"file":"apartment-with-private-pool-makarska-5-818x417.jpg","width":818,"height":417,"mime-type":"image\/jpeg","filesize":57823,"url":"https:\/\/www.croatia-property.net\/wp-content\/uploads\/2025\/12\/apartment-with-private-pool-makarska-5-818x417.jpg"},"agent-image":{"file":"apartment-with-private-pool-makarska-5-210x210.jpg","width":210,"height":210,"mime-type":"image\/jpeg","filesize":11312,"url":"https:\/\/www.croatia-property.net\/wp-content\/uploads\/2025\/12\/apartment-with-private-pool-makarska-5-210x210.jpg"},"partners-logo":{"file":"apartment-with-private-pool-makarska-5-600x683.jpg","width":600,"height":683,"mime-type":"image\/jpeg","filesize":73285,"url":"https:\/\/www.croatia-property.net\/wp-content\/uploads\/2025\/12\/apartment-with-private-pool-makarska-5-600x683.jpg"},"gallery-two-column-image":{"file":"apartment-with-private-pool-makarska-5-536x269.jpg","width":536,"height":269,"mime-type":"image\/jpeg","filesize":28993,"url":"https:\/\/www.croatia-property.net\/wp-content\/uploads\/2025\/12\/apartment-with-private-pool-makarska-5-536x269.jpg"},"property-detail-slider-image-two":{"file":"apartment-with-private-pool-makarska-5-1024x648.jpg","width":1024,"height":648,"mime-type":"image\/jpeg","filesize":107291,"url":"https:\/\/www.croatia-property.net\/wp-content\/uploads\/2025\/12\/apartment-with-private-pool-makarska-5-1024x648.jpg"},"property-detail-slider-thumb":{"file":"apartment-with-private-pool-makarska-5-82x60.jpg","width":82,"height":60,"mime-type":"image\/jpeg","filesize":2603,"url":"https:\/\/www.croatia-property.net\/wp-content\/uploads\/2025\/12\/apartment-with-private-pool-makarska-5-82x60.jpg"}},"image_meta":{"aperture":"2.2","credit":"","camera":"Galaxy A54 5G","caption":"","created_timestamp":"1765445710","copyright":"","focal_length":"1.74","iso":"160","shutter_speed":"0.02","title":"","orientation":"1","keywords":[]},"ID":"164225","name":"apartment-with-private-pool-makarska-5.jpg","path":"\/home\/gagwyweu\/public_html\/wp-content\/uploads\/2025\/12\/apartment-with-private-pool-makarska-5.jpg","url":"https:\/\/www.croatia-property.net\/wp-content\/uploads\/2025\/12\/apartment-with-private-pool-makarska-5-150x150.jpg","full_url":"https:\/\/www.croatia-property.net\/wp-content\/uploads\/2025\/12\/apartment-with-private-pool-makarska-5.jpg","title":"apartment with private pool makarska (5)","caption":"apartment with private pool makarska - 3545 - photo (5)","description":"","alt":"apartment with private pool makarska - 3545 (5)","srcset":"https:\/\/www.croatia-property.net\/wp-content\/uploads\/2025\/12\/apartment-with-private-pool-makarska-5-150x150.jpg 150w, https:\/\/www.croatia-property.net\/wp-content\/uploads\/2025\/12\/apartment-with-private-pool-makarska-5-210x210.jpg 210w"},{"width":150,"height":150,"file":"2025\/12\/apartment-with-private-pool-makarska-6.jpg","filesize":160066,"sizes":{"medium":{"file":"apartment-with-private-pool-makarska-6-300x200.jpg","width":300,"height":200,"mime-type":"image\/jpeg","filesize":12493,"url":"https:\/\/www.croatia-property.net\/wp-content\/uploads\/2025\/12\/apartment-with-private-pool-makarska-6-300x200.jpg"},"thumbnail":{"file":"apartment-with-private-pool-makarska-6-150x150.jpg","width":150,"height":150,"mime-type":"image\/jpeg","filesize":6154,"url":"https:\/\/www.croatia-property.net\/wp-content\/uploads\/2025\/12\/apartment-with-private-pool-makarska-6-150x150.jpg"},"medium_large":{"file":"apartment-with-private-pool-makarska-6-768x512.jpg","width":768,"height":512,"mime-type":"image\/jpeg","filesize":52686,"url":"https:\/\/www.croatia-property.net\/wp-content\/uploads\/2025\/12\/apartment-with-private-pool-makarska-6-768x512.jpg"},"post-thumbnail":{"file":"apartment-with-private-pool-makarska-6-150x100.jpg","width":150,"height":100,"mime-type":"image\/jpeg","filesize":4756,"url":"https:\/\/www.croatia-property.net\/wp-content\/uploads\/2025\/12\/apartment-with-private-pool-makarska-6-150x100.jpg"},"modern-property-child-slider":{"file":"apartment-with-private-pool-makarska-6-680x510.jpg","width":680,"height":510,"mime-type":"image\/jpeg","filesize":49003,"url":"https:\/\/www.croatia-property.net\/wp-content\/uploads\/2025\/12\/apartment-with-private-pool-makarska-6-680x510.jpg"},"property-thumb-image":{"file":"apartment-with-private-pool-makarska-6-488x326.jpg","width":488,"height":326,"mime-type":"image\/jpeg","filesize":26059,"url":"https:\/\/www.croatia-property.net\/wp-content\/uploads\/2025\/12\/apartment-with-private-pool-makarska-6-488x326.jpg"},"property-detail-video-image":{"file":"apartment-with-private-pool-makarska-6-818x417.jpg","width":818,"height":417,"mime-type":"image\/jpeg","filesize":47964,"url":"https:\/\/www.croatia-property.net\/wp-content\/uploads\/2025\/12\/apartment-with-private-pool-makarska-6-818x417.jpg"},"agent-image":{"file":"apartment-with-private-pool-makarska-6-210x210.jpg","width":210,"height":210,"mime-type":"image\/jpeg","filesize":10120,"url":"https:\/\/www.croatia-property.net\/wp-content\/uploads\/2025\/12\/apartment-with-private-pool-makarska-6-210x210.jpg"},"partners-logo":{"file":"apartment-with-private-pool-makarska-6-600x683.jpg","width":600,"height":683,"mime-type":"image\/jpeg","filesize":59906,"url":"https:\/\/www.croatia-property.net\/wp-content\/uploads\/2025\/12\/apartment-with-private-pool-makarska-6-600x683.jpg"},"gallery-two-column-image":{"file":"apartment-with-private-pool-makarska-6-536x269.jpg","width":536,"height":269,"mime-type":"image\/jpeg","filesize":24472,"url":"https:\/\/www.croatia-property.net\/wp-content\/uploads\/2025\/12\/apartment-with-private-pool-makarska-6-536x269.jpg"},"property-detail-slider-image-two":{"file":"apartment-with-private-pool-makarska-6-1024x648.jpg","width":1024,"height":648,"mime-type":"image\/jpeg","filesize":86891,"url":"https:\/\/www.croatia-property.net\/wp-content\/uploads\/2025\/12\/apartment-with-private-pool-makarska-6-1024x648.jpg"},"property-detail-slider-thumb":{"file":"apartment-with-private-pool-makarska-6-82x60.jpg","width":82,"height":60,"mime-type":"image\/jpeg","filesize":2401,"url":"https:\/\/www.croatia-property.net\/wp-content\/uploads\/2025\/12\/apartment-with-private-pool-makarska-6-82x60.jpg"}},"image_meta":{"aperture":"2.2","credit":"","camera":"Galaxy A54 5G","caption":"","created_timestamp":"1765445737","copyright":"","focal_length":"1.74","iso":"200","shutter_speed":"0.02","title":"","orientation":"1","keywords":[]},"ID":"164228","name":"apartment-with-private-pool-makarska-6.jpg","path":"\/home\/gagwyweu\/public_html\/wp-content\/uploads\/2025\/12\/apartment-with-private-pool-makarska-6.jpg","url":"https:\/\/www.croatia-property.net\/wp-content\/uploads\/2025\/12\/apartment-with-private-pool-makarska-6-150x150.jpg","full_url":"https:\/\/www.croatia-property.net\/wp-content\/uploads\/2025\/12\/apartment-with-private-pool-makarska-6.jpg","title":"apartment with private pool makarska (6)","caption":"apartment with private pool makarska - 3545 - photo (6)","description":"","alt":"apartment with private pool makarska - 3545 (6)","srcset":"https:\/\/www.croatia-property.net\/wp-content\/uploads\/2025\/12\/apartment-with-private-pool-makarska-6-150x150.jpg 150w, https:\/\/www.croatia-property.net\/wp-content\/uploads\/2025\/12\/apartment-with-private-pool-makarska-6-210x210.jpg 210w"},{"width":150,"height":150,"file":"2025\/12\/apartment-with-private-pool-makarska-7.jpg","filesize":151046,"sizes":{"medium":{"file":"apartment-with-private-pool-makarska-7-300x200.jpg","width":300,"height":200,"mime-type":"image\/jpeg","filesize":12373,"url":"https:\/\/www.croatia-property.net\/wp-content\/uploads\/2025\/12\/apartment-with-private-pool-makarska-7-300x200.jpg"},"thumbnail":{"file":"apartment-with-private-pool-makarska-7-150x150.jpg","width":150,"height":150,"mime-type":"image\/jpeg","filesize":5867,"url":"https:\/\/www.croatia-property.net\/wp-content\/uploads\/2025\/12\/apartment-with-private-pool-makarska-7-150x150.jpg"},"medium_large":{"file":"apartment-with-private-pool-makarska-7-768x512.jpg","width":768,"height":512,"mime-type":"image\/jpeg","filesize":51437,"url":"https:\/\/www.croatia-property.net\/wp-content\/uploads\/2025\/12\/apartment-with-private-pool-makarska-7-768x512.jpg"},"post-thumbnail":{"file":"apartment-with-private-pool-makarska-7-150x100.jpg","width":150,"height":100,"mime-type":"image\/jpeg","filesize":4622,"url":"https:\/\/www.croatia-property.net\/wp-content\/uploads\/2025\/12\/apartment-with-private-pool-makarska-7-150x100.jpg"},"modern-property-child-slider":{"file":"apartment-with-private-pool-makarska-7-680x510.jpg","width":680,"height":510,"mime-type":"image\/jpeg","filesize":45922,"url":"https:\/\/www.croatia-property.net\/wp-content\/uploads\/2025\/12\/apartment-with-private-pool-makarska-7-680x510.jpg"},"property-thumb-image":{"file":"apartment-with-private-pool-makarska-7-488x326.jpg","width":488,"height":326,"mime-type":"image\/jpeg","filesize":25854,"url":"https:\/\/www.croatia-property.net\/wp-content\/uploads\/2025\/12\/apartment-with-private-pool-makarska-7-488x326.jpg"},"property-detail-video-image":{"file":"apartment-with-private-pool-makarska-7-818x417.jpg","width":818,"height":417,"mime-type":"image\/jpeg","filesize":47280,"url":"https:\/\/www.croatia-property.net\/wp-content\/uploads\/2025\/12\/apartment-with-private-pool-makarska-7-818x417.jpg"},"agent-image":{"file":"apartment-with-private-pool-makarska-7-210x210.jpg","width":210,"height":210,"mime-type":"image\/jpeg","filesize":9665,"url":"https:\/\/www.croatia-property.net\/wp-content\/uploads\/2025\/12\/apartment-with-private-pool-makarska-7-210x210.jpg"},"partners-logo":{"file":"apartment-with-private-pool-makarska-7-600x683.jpg","width":600,"height":683,"mime-type":"image\/jpeg","filesize":54079,"url":"https:\/\/www.croatia-property.net\/wp-content\/uploads\/2025\/12\/apartment-with-private-pool-makarska-7-600x683.jpg"},"gallery-two-column-image":{"file":"apartment-with-private-pool-makarska-7-536x269.jpg","width":536,"height":269,"mime-type":"image\/jpeg","filesize":24510,"url":"https:\/\/www.croatia-property.net\/wp-content\/uploads\/2025\/12\/apartment-with-private-pool-makarska-7-536x269.jpg"},"property-detail-slider-image-two":{"file":"apartment-with-private-pool-makarska-7-1024x648.jpg","width":1024,"height":648,"mime-type":"image\/jpeg","filesize":83643,"url":"https:\/\/www.croatia-property.net\/wp-content\/uploads\/2025\/12\/apartment-with-private-pool-makarska-7-1024x648.jpg"},"property-detail-slider-thumb":{"file":"apartment-with-private-pool-makarska-7-82x60.jpg","width":82,"height":60,"mime-type":"image\/jpeg","filesize":2289,"url":"https:\/\/www.croatia-property.net\/wp-content\/uploads\/2025\/12\/apartment-with-private-pool-makarska-7-82x60.jpg"}},"image_meta":{"aperture":"2.2","credit":"","camera":"Galaxy A54 5G","caption":"","created_timestamp":"1765445757","copyright":"","focal_length":"1.74","iso":"160","shutter_speed":"0.03030303030303","title":"","orientation":"1","keywords":[]},"ID":"164231","name":"apartment-with-private-pool-makarska-7.jpg","path":"\/home\/gagwyweu\/public_html\/wp-content\/uploads\/2025\/12\/apartment-with-private-pool-makarska-7.jpg","url":"https:\/\/www.croatia-property.net\/wp-content\/uploads\/2025\/12\/apartment-with-private-pool-makarska-7-150x150.jpg","full_url":"https:\/\/www.croatia-property.net\/wp-content\/uploads\/2025\/12\/apartment-with-private-pool-makarska-7.jpg","title":"apartment with private pool makarska (7)","caption":"apartment with private pool makarska - 3545 - photo (7)","description":"","alt":"apartment with private pool makarska - 3545 (7)","srcset":"https:\/\/www.croatia-property.net\/wp-content\/uploads\/2025\/12\/apartment-with-private-pool-makarska-7-150x150.jpg 150w, https:\/\/www.croatia-property.net\/wp-content\/uploads\/2025\/12\/apartment-with-private-pool-makarska-7-210x210.jpg 210w"},{"width":150,"height":150,"file":"2025\/12\/apartment-with-private-pool-makarska-8.jpg","filesize":154436,"sizes":{"medium":{"file":"apartment-with-private-pool-makarska-8-300x200.jpg","width":300,"height":200,"mime-type":"image\/jpeg","filesize":12205,"url":"https:\/\/www.croatia-property.net\/wp-content\/uploads\/2025\/12\/apartment-with-private-pool-makarska-8-300x200.jpg"},"thumbnail":{"file":"apartment-with-private-pool-makarska-8-150x150.jpg","width":150,"height":150,"mime-type":"image\/jpeg","filesize":5901,"url":"https:\/\/www.croatia-property.net\/wp-content\/uploads\/2025\/12\/apartment-with-private-pool-makarska-8-150x150.jpg"},"medium_large":{"file":"apartment-with-private-pool-makarska-8-768x512.jpg","width":768,"height":512,"mime-type":"image\/jpeg","filesize":50864,"url":"https:\/\/www.croatia-property.net\/wp-content\/uploads\/2025\/12\/apartment-with-private-pool-makarska-8-768x512.jpg"},"post-thumbnail":{"file":"apartment-with-private-pool-makarska-8-150x100.jpg","width":150,"height":100,"mime-type":"image\/jpeg","filesize":4571,"url":"https:\/\/www.croatia-property.net\/wp-content\/uploads\/2025\/12\/apartment-with-private-pool-makarska-8-150x100.jpg"},"modern-property-child-slider":{"file":"apartment-with-private-pool-makarska-8-680x510.jpg","width":680,"height":510,"mime-type":"image\/jpeg","filesize":46442,"url":"https:\/\/www.croatia-property.net\/wp-content\/uploads\/2025\/12\/apartment-with-private-pool-makarska-8-680x510.jpg"},"property-thumb-image":{"file":"apartment-with-private-pool-makarska-8-488x326.jpg","width":488,"height":326,"mime-type":"image\/jpeg","filesize":25491,"url":"https:\/\/www.croatia-property.net\/wp-content\/uploads\/2025\/12\/apartment-with-private-pool-makarska-8-488x326.jpg"},"property-detail-video-image":{"file":"apartment-with-private-pool-makarska-8-818x417.jpg","width":818,"height":417,"mime-type":"image\/jpeg","filesize":44033,"url":"https:\/\/www.croatia-property.net\/wp-content\/uploads\/2025\/12\/apartment-with-private-pool-makarska-8-818x417.jpg"},"agent-image":{"file":"apartment-with-private-pool-makarska-8-210x210.jpg","width":210,"height":210,"mime-type":"image\/jpeg","filesize":9788,"url":"https:\/\/www.croatia-property.net\/wp-content\/uploads\/2025\/12\/apartment-with-private-pool-makarska-8-210x210.jpg"},"partners-logo":{"file":"apartment-with-private-pool-makarska-8-600x683.jpg","width":600,"height":683,"mime-type":"image\/jpeg","filesize":55131,"url":"https:\/\/www.croatia-property.net\/wp-content\/uploads\/2025\/12\/apartment-with-private-pool-makarska-8-600x683.jpg"},"gallery-two-column-image":{"file":"apartment-with-private-pool-makarska-8-536x269.jpg","width":536,"height":269,"mime-type":"image\/jpeg","filesize":22431,"url":"https:\/\/www.croatia-property.net\/wp-content\/uploads\/2025\/12\/apartment-with-private-pool-makarska-8-536x269.jpg"},"property-detail-slider-image-two":{"file":"apartment-with-private-pool-makarska-8-1024x648.jpg","width":1024,"height":648,"mime-type":"image\/jpeg","filesize":82167,"url":"https:\/\/www.croatia-property.net\/wp-content\/uploads\/2025\/12\/apartment-with-private-pool-makarska-8-1024x648.jpg"},"property-detail-slider-thumb":{"file":"apartment-with-private-pool-makarska-8-82x60.jpg","width":82,"height":60,"mime-type":"image\/jpeg","filesize":2302,"url":"https:\/\/www.croatia-property.net\/wp-content\/uploads\/2025\/12\/apartment-with-private-pool-makarska-8-82x60.jpg"}},"image_meta":{"aperture":"2.2","credit":"","camera":"Galaxy A54 5G","caption":"","created_timestamp":"1765445767","copyright":"","focal_length":"1.74","iso":"64","shutter_speed":"0.025","title":"","orientation":"1","keywords":[]},"ID":"164234","name":"apartment-with-private-pool-makarska-8.jpg","path":"\/home\/gagwyweu\/public_html\/wp-content\/uploads\/2025\/12\/apartment-with-private-pool-makarska-8.jpg","url":"https:\/\/www.croatia-property.net\/wp-content\/uploads\/2025\/12\/apartment-with-private-pool-makarska-8-150x150.jpg","full_url":"https:\/\/www.croatia-property.net\/wp-content\/uploads\/2025\/12\/apartment-with-private-pool-makarska-8.jpg","title":"apartment with private pool makarska (8)","caption":"apartment with private pool makarska - 3545 - photo (8)","description":"","alt":"apartment with private pool makarska - 3545 (8)","srcset":"https:\/\/www.croatia-property.net\/wp-content\/uploads\/2025\/12\/apartment-with-private-pool-makarska-8-150x150.jpg 150w, https:\/\/www.croatia-property.net\/wp-content\/uploads\/2025\/12\/apartment-with-private-pool-makarska-8-210x210.jpg 210w"},{"width":150,"height":150,"file":"2025\/12\/apartment-with-private-pool-makarska-9.jpg","filesize":124153,"sizes":{"medium":{"file":"apartment-with-private-pool-makarska-9-300x200.jpg","width":300,"height":200,"mime-type":"image\/jpeg","filesize":8891,"url":"https:\/\/www.croatia-property.net\/wp-content\/uploads\/2025\/12\/apartment-with-private-pool-makarska-9-300x200.jpg"},"thumbnail":{"file":"apartment-with-private-pool-makarska-9-150x150.jpg","width":150,"height":150,"mime-type":"image\/jpeg","filesize":4851,"url":"https:\/\/www.croatia-property.net\/wp-content\/uploads\/2025\/12\/apartment-with-private-pool-makarska-9-150x150.jpg"},"medium_large":{"file":"apartment-with-private-pool-makarska-9-768x512.jpg","width":768,"height":512,"mime-type":"image\/jpeg","filesize":40268,"url":"https:\/\/www.croatia-property.net\/wp-content\/uploads\/2025\/12\/apartment-with-private-pool-makarska-9-768x512.jpg"},"post-thumbnail":{"file":"apartment-with-private-pool-makarska-9-150x100.jpg","width":150,"height":100,"mime-type":"image\/jpeg","filesize":3482,"url":"https:\/\/www.croatia-property.net\/wp-content\/uploads\/2025\/12\/apartment-with-private-pool-makarska-9-150x100.jpg"},"modern-property-child-slider":{"file":"apartment-with-private-pool-makarska-9-680x510.jpg","width":680,"height":510,"mime-type":"image\/jpeg","filesize":38032,"url":"https:\/\/www.croatia-property.net\/wp-content\/uploads\/2025\/12\/apartment-with-private-pool-makarska-9-680x510.jpg"},"property-thumb-image":{"file":"apartment-with-private-pool-makarska-9-488x326.jpg","width":488,"height":326,"mime-type":"image\/jpeg","filesize":19089,"url":"https:\/\/www.croatia-property.net\/wp-content\/uploads\/2025\/12\/apartment-with-private-pool-makarska-9-488x326.jpg"},"property-detail-video-image":{"file":"apartment-with-private-pool-makarska-9-818x417.jpg","width":818,"height":417,"mime-type":"image\/jpeg","filesize":36275,"url":"https:\/\/www.croatia-property.net\/wp-content\/uploads\/2025\/12\/apartment-with-private-pool-makarska-9-818x417.jpg"},"agent-image":{"file":"apartment-with-private-pool-makarska-9-210x210.jpg","width":210,"height":210,"mime-type":"image\/jpeg","filesize":8127,"url":"https:\/\/www.croatia-property.net\/wp-content\/uploads\/2025\/12\/apartment-with-private-pool-makarska-9-210x210.jpg"},"partners-logo":{"file":"apartment-with-private-pool-makarska-9-600x683.jpg","width":600,"height":683,"mime-type":"image\/jpeg","filesize":55580,"url":"https:\/\/www.croatia-property.net\/wp-content\/uploads\/2025\/12\/apartment-with-private-pool-makarska-9-600x683.jpg"},"gallery-two-column-image":{"file":"apartment-with-private-pool-makarska-9-536x269.jpg","width":536,"height":269,"mime-type":"image\/jpeg","filesize":18000,"url":"https:\/\/www.croatia-property.net\/wp-content\/uploads\/2025\/12\/apartment-with-private-pool-makarska-9-536x269.jpg"},"property-detail-slider-image-two":{"file":"apartment-with-private-pool-makarska-9-1024x648.jpg","width":1024,"height":648,"mime-type":"image\/jpeg","filesize":68406,"url":"https:\/\/www.croatia-property.net\/wp-content\/uploads\/2025\/12\/apartment-with-private-pool-makarska-9-1024x648.jpg"},"property-detail-slider-thumb":{"file":"apartment-with-private-pool-makarska-9-82x60.jpg","width":82,"height":60,"mime-type":"image\/jpeg","filesize":1924,"url":"https:\/\/www.croatia-property.net\/wp-content\/uploads\/2025\/12\/apartment-with-private-pool-makarska-9-82x60.jpg"}},"image_meta":{"aperture":"2.2","credit":"","camera":"Galaxy A54 5G","caption":"","created_timestamp":"1765445781","copyright":"","focal_length":"1.74","iso":"125","shutter_speed":"0.02","title":"","orientation":"1","keywords":[]},"ID":"164237","name":"apartment-with-private-pool-makarska-9.jpg","path":"\/home\/gagwyweu\/public_html\/wp-content\/uploads\/2025\/12\/apartment-with-private-pool-makarska-9.jpg","url":"https:\/\/www.croatia-property.net\/wp-content\/uploads\/2025\/12\/apartment-with-private-pool-makarska-9-150x150.jpg","full_url":"https:\/\/www.croatia-property.net\/wp-content\/uploads\/2025\/12\/apartment-with-private-pool-makarska-9.jpg","title":"apartment with private pool makarska (9)","caption":"apartment with private pool makarska - 3545 - photo (9)","description":"","alt":"apartment with private pool makarska - 3545 (9)","srcset":"https:\/\/www.croatia-property.net\/wp-content\/uploads\/2025\/12\/apartment-with-private-pool-makarska-9-150x150.jpg 150w, https:\/\/www.croatia-property.net\/wp-content\/uploads\/2025\/12\/apartment-with-private-pool-makarska-9-210x210.jpg 210w"},{"width":150,"height":150,"file":"2025\/12\/apartment-with-private-pool-makarska-10.jpg","filesize":125581,"sizes":{"medium":{"file":"apartment-with-private-pool-makarska-10-300x200.jpg","width":300,"height":200,"mime-type":"image\/jpeg","filesize":10172,"url":"https:\/\/www.croatia-property.net\/wp-content\/uploads\/2025\/12\/apartment-with-private-pool-makarska-10-300x200.jpg"},"thumbnail":{"file":"apartment-with-private-pool-makarska-10-150x150.jpg","width":150,"height":150,"mime-type":"image\/jpeg","filesize":5492,"url":"https:\/\/www.croatia-property.net\/wp-content\/uploads\/2025\/12\/apartment-with-private-pool-makarska-10-150x150.jpg"},"medium_large":{"file":"apartment-with-private-pool-makarska-10-768x512.jpg","width":768,"height":512,"mime-type":"image\/jpeg","filesize":42315,"url":"https:\/\/www.croatia-property.net\/wp-content\/uploads\/2025\/12\/apartment-with-private-pool-makarska-10-768x512.jpg"},"post-thumbnail":{"file":"apartment-with-private-pool-makarska-10-150x100.jpg","width":150,"height":100,"mime-type":"image\/jpeg","filesize":3939,"url":"https:\/\/www.croatia-property.net\/wp-content\/uploads\/2025\/12\/apartment-with-private-pool-makarska-10-150x100.jpg"},"modern-property-child-slider":{"file":"apartment-with-private-pool-makarska-10-680x510.jpg","width":680,"height":510,"mime-type":"image\/jpeg","filesize":39363,"url":"https:\/\/www.croatia-property.net\/wp-content\/uploads\/2025\/12\/apartment-with-private-pool-makarska-10-680x510.jpg"},"property-thumb-image":{"file":"apartment-with-private-pool-makarska-10-488x326.jpg","width":488,"height":326,"mime-type":"image\/jpeg","filesize":21024,"url":"https:\/\/www.croatia-property.net\/wp-content\/uploads\/2025\/12\/apartment-with-private-pool-makarska-10-488x326.jpg"},"property-detail-video-image":{"file":"apartment-with-private-pool-makarska-10-818x417.jpg","width":818,"height":417,"mime-type":"image\/jpeg","filesize":38377,"url":"https:\/\/www.croatia-property.net\/wp-content\/uploads\/2025\/12\/apartment-with-private-pool-makarska-10-818x417.jpg"},"agent-image":{"file":"apartment-with-private-pool-makarska-10-210x210.jpg","width":210,"height":210,"mime-type":"image\/jpeg","filesize":8891,"url":"https:\/\/www.croatia-property.net\/wp-content\/uploads\/2025\/12\/apartment-with-private-pool-makarska-10-210x210.jpg"},"partners-logo":{"file":"apartment-with-private-pool-makarska-10-600x683.jpg","width":600,"height":683,"mime-type":"image\/jpeg","filesize":53192,"url":"https:\/\/www.croatia-property.net\/wp-content\/uploads\/2025\/12\/apartment-with-private-pool-makarska-10-600x683.jpg"},"gallery-two-column-image":{"file":"apartment-with-private-pool-makarska-10-536x269.jpg","width":536,"height":269,"mime-type":"image\/jpeg","filesize":19613,"url":"https:\/\/www.croatia-property.net\/wp-content\/uploads\/2025\/12\/apartment-with-private-pool-makarska-10-536x269.jpg"},"property-detail-slider-image-two":{"file":"apartment-with-private-pool-makarska-10-1024x648.jpg","width":1024,"height":648,"mime-type":"image\/jpeg","filesize":68284,"url":"https:\/\/www.croatia-property.net\/wp-content\/uploads\/2025\/12\/apartment-with-private-pool-makarska-10-1024x648.jpg"},"property-detail-slider-thumb":{"file":"apartment-with-private-pool-makarska-10-82x60.jpg","width":82,"height":60,"mime-type":"image\/jpeg","filesize":2089,"url":"https:\/\/www.croatia-property.net\/wp-content\/uploads\/2025\/12\/apartment-with-private-pool-makarska-10-82x60.jpg"}},"image_meta":{"aperture":"2.2","credit":"","camera":"Galaxy A54 5G","caption":"","created_timestamp":"1765445787","copyright":"","focal_length":"1.74","iso":"64","shutter_speed":"0.02","title":"","orientation":"1","keywords":[]},"ID":"164240","name":"apartment-with-private-pool-makarska-10.jpg","path":"\/home\/gagwyweu\/public_html\/wp-content\/uploads\/2025\/12\/apartment-with-private-pool-makarska-10.jpg","url":"https:\/\/www.croatia-property.net\/wp-content\/uploads\/2025\/12\/apartment-with-private-pool-makarska-10-150x150.jpg","full_url":"https:\/\/www.croatia-property.net\/wp-content\/uploads\/2025\/12\/apartment-with-private-pool-makarska-10.jpg","title":"apartment with private pool makarska (10)","caption":"apartment with private pool makarska - 3545 - photo (10)","description":"","alt":"apartment with private pool makarska - 3545 (10)","srcset":"https:\/\/www.croatia-property.net\/wp-content\/uploads\/2025\/12\/apartment-with-private-pool-makarska-10-150x150.jpg 150w, https:\/\/www.croatia-property.net\/wp-content\/uploads\/2025\/12\/apartment-with-private-pool-makarska-10-210x210.jpg 210w"},{"width":150,"height":150,"file":"2025\/12\/apartment-with-private-pool-makarska-11.jpg","filesize":149887,"sizes":{"medium":{"file":"apartment-with-private-pool-makarska-11-300x200.jpg","width":300,"height":200,"mime-type":"image\/jpeg","filesize":12307,"url":"https:\/\/www.croatia-property.net\/wp-content\/uploads\/2025\/12\/apartment-with-private-pool-makarska-11-300x200.jpg"},"thumbnail":{"file":"apartment-with-private-pool-makarska-11-150x150.jpg","width":150,"height":150,"mime-type":"image\/jpeg","filesize":5691,"url":"https:\/\/www.croatia-property.net\/wp-content\/uploads\/2025\/12\/apartment-with-private-pool-makarska-11-150x150.jpg"},"medium_large":{"file":"apartment-with-private-pool-makarska-11-768x512.jpg","width":768,"height":512,"mime-type":"image\/jpeg","filesize":50483,"url":"https:\/\/www.croatia-property.net\/wp-content\/uploads\/2025\/12\/apartment-with-private-pool-makarska-11-768x512.jpg"},"post-thumbnail":{"file":"apartment-with-private-pool-makarska-11-150x100.jpg","width":150,"height":100,"mime-type":"image\/jpeg","filesize":4722,"url":"https:\/\/www.croatia-property.net\/wp-content\/uploads\/2025\/12\/apartment-with-private-pool-makarska-11-150x100.jpg"},"modern-property-child-slider":{"file":"apartment-with-private-pool-makarska-11-680x510.jpg","width":680,"height":510,"mime-type":"image\/jpeg","filesize":44898,"url":"https:\/\/www.croatia-property.net\/wp-content\/uploads\/2025\/12\/apartment-with-private-pool-makarska-11-680x510.jpg"},"property-thumb-image":{"file":"apartment-with-private-pool-makarska-11-488x326.jpg","width":488,"height":326,"mime-type":"image\/jpeg","filesize":25396,"url":"https:\/\/www.croatia-property.net\/wp-content\/uploads\/2025\/12\/apartment-with-private-pool-makarska-11-488x326.jpg"},"property-detail-video-image":{"file":"apartment-with-private-pool-makarska-11-818x417.jpg","width":818,"height":417,"mime-type":"image\/jpeg","filesize":47365,"url":"https:\/\/www.croatia-property.net\/wp-content\/uploads\/2025\/12\/apartment-with-private-pool-makarska-11-818x417.jpg"},"agent-image":{"file":"apartment-with-private-pool-makarska-11-210x210.jpg","width":210,"height":210,"mime-type":"image\/jpeg","filesize":9318,"url":"https:\/\/www.croatia-property.net\/wp-content\/uploads\/2025\/12\/apartment-with-private-pool-makarska-11-210x210.jpg"},"partners-logo":{"file":"apartment-with-private-pool-makarska-11-600x683.jpg","width":600,"height":683,"mime-type":"image\/jpeg","filesize":54842,"url":"https:\/\/www.croatia-property.net\/wp-content\/uploads\/2025\/12\/apartment-with-private-pool-makarska-11-600x683.jpg"},"gallery-two-column-image":{"file":"apartment-with-private-pool-makarska-11-536x269.jpg","width":536,"height":269,"mime-type":"image\/jpeg","filesize":24521,"url":"https:\/\/www.croatia-property.net\/wp-content\/uploads\/2025\/12\/apartment-with-private-pool-makarska-11-536x269.jpg"},"property-detail-slider-image-two":{"file":"apartment-with-private-pool-makarska-11-1024x648.jpg","width":1024,"height":648,"mime-type":"image\/jpeg","filesize":82436,"url":"https:\/\/www.croatia-property.net\/wp-content\/uploads\/2025\/12\/apartment-with-private-pool-makarska-11-1024x648.jpg"},"property-detail-slider-thumb":{"file":"apartment-with-private-pool-makarska-11-82x60.jpg","width":82,"height":60,"mime-type":"image\/jpeg","filesize":2345,"url":"https:\/\/www.croatia-property.net\/wp-content\/uploads\/2025\/12\/apartment-with-private-pool-makarska-11-82x60.jpg"}},"image_meta":{"aperture":"2.2","credit":"","camera":"Galaxy A54 5G","caption":"","created_timestamp":"1765445859","copyright":"","focal_length":"1.74","iso":"40","shutter_speed":"0.02","title":"","orientation":"1","keywords":[]},"ID":"164243","name":"apartment-with-private-pool-makarska-11.jpg","path":"\/home\/gagwyweu\/public_html\/wp-content\/uploads\/2025\/12\/apartment-with-private-pool-makarska-11.jpg","url":"https:\/\/www.croatia-property.net\/wp-content\/uploads\/2025\/12\/apartment-with-private-pool-makarska-11-150x150.jpg","full_url":"https:\/\/www.croatia-property.net\/wp-content\/uploads\/2025\/12\/apartment-with-private-pool-makarska-11.jpg","title":"apartment with private pool makarska (11)","caption":"apartment with private pool makarska - 3545 - photo (11)","description":"","alt":"apartment with private pool makarska - 3545 (11)","srcset":"https:\/\/www.croatia-property.net\/wp-content\/uploads\/2025\/12\/apartment-with-private-pool-makarska-11-150x150.jpg 150w, https:\/\/www.croatia-property.net\/wp-content\/uploads\/2025\/12\/apartment-with-private-pool-makarska-11-210x210.jpg 210w"}],"REAL_HOMES_change_gallery_slider_type":"","REAL_HOMES_gallery_slider_type":"thumb-on-right","inspiry_floor_plans":[],"inspiry_video_group":[],"REAL_HOMES_360_virtual_tour":"","REAL_HOMES_agent_display_option":"none","REAL_HOMES_agents":[],"REAL_HOMES_energy_class":"","REAL_HOMES_energy_performance":"","REAL_HOMES_epc_current_rating":"","REAL_HOMES_epc_potential_rating":"","ere_property_schedule_tour":"","ere_property_schedule_time_slots":"","ere_property_schedule_description":"","REAL_HOMES_sticky":"","inspiry_property_label":"","inspiry_property_label_color":"","inspiry_property_tax":"","inspiry_additional_fee":"","REAL_HOMES_attachments":[],"inspiry_property_owner_name":"","inspiry_property_owner_contact":"","inspiry_property_owner_address":"","REAL_HOMES_property_private_note":"","inspiry_message_to_reviewer":"","REAL_HOMES_add_in_slider":"no","REAL_HOMES_slider_image":[],"REAL_HOMES_page_banner_image":[],"inspiry_parking_spaces":"","REAL_HOMES_custom_header_display":"","REAL_HOMES_custom_header_position":"","REAL_HOMES_custom_footer_display":""},"_links":{"self":[{"href":"https:\/\/www.croatia-property.net\/de\/wp-json\/wp\/v2\/property\/164247","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.croatia-property.net\/de\/wp-json\/wp\/v2\/property"}],"about":[{"href":"https:\/\/www.croatia-property.net\/de\/wp-json\/wp\/v2\/types\/property"}],"author":[{"embeddable":true,"href":"https:\/\/www.croatia-property.net\/de\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/www.croatia-property.net\/de\/wp-json\/wp\/v2\/comments?post=164247"}],"version-history":[{"count":1,"href":"https:\/\/www.croatia-property.net\/de\/wp-json\/wp\/v2\/property\/164247\/revisions"}],"predecessor-version":[{"id":164248,"href":"https:\/\/www.croatia-property.net\/de\/wp-json\/wp\/v2\/property\/164247\/revisions\/164248"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.croatia-property.net\/de\/wp-json\/wp\/v2\/media\/164211"}],"wp:attachment":[{"href":"https:\/\/www.croatia-property.net\/de\/wp-json\/wp\/v2\/media?parent=164247"}],"wp:term":[{"taxonomy":"property-feature","embeddable":true,"href":"https:\/\/www.croatia-property.net\/de\/wp-json\/wp\/v2\/property-feature?post=164247"},{"taxonomy":"property-type","embeddable":true,"href":"https:\/\/www.croatia-property.net\/de\/wp-json\/wp\/v2\/property-type?post=164247"},{"taxonomy":"property-city","embeddable":true,"href":"https:\/\/www.croatia-property.net\/de\/wp-json\/wp\/v2\/property-city?post=164247"},{"taxonomy":"property-status","embeddable":true,"href":"https:\/\/www.croatia-property.net\/de\/wp-json\/wp\/v2\/property-status?post=164247"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}