{"id":188,"count":13,"description":"Viele halten Vis f\u00fcr eine der sch\u00f6nsten kroatischen Inseln. Seine reiche Geschichte reicht bis in die Vorgeschichte zur\u00fcck, mit vielen Fundamenten aus der Altsteinzeit. Issa, eine sehr wichtige Siedlung aus der griechischen und r\u00f6mischen Zeit, war eine der bedeutendsten antiken St\u00e4dte am Mittelmeer. Die Stadt hatte ihr eigenes Geld, ihre eigene Flotte und ihre eigenen Kolonien, was sie zu einem sehr einflussreichen historischen Ort machte. Die heutigen Ruinen sind ein wahres Beispiel f\u00fcr die glorreiche Geschichte dieser Insel. W\u00e4hrend des Mittelalters und der Renaissance stand Vis unter venezianischer Herrschaft, und nach der franz\u00f6sischen, englischen und \u00f6sterreichischen Regierung erlebte Vis nach dem Zweiten Weltkrieg endlich eine Zeit des Friedens. W\u00e4hrend dieser Jahre stand Vis unter enormem milit\u00e4rischem Einfluss, was es Ausl\u00e4ndern praktisch unm\u00f6glich machte, sie zu besuchen. Erst 1989 durften Ausl\u00e4nder zu diesem mediterranen Juwel kommen. Daher ist Vis vom Tourismus in der Tat unber\u00fchrt geblieben. Deshalb ist es bei Touristen sehr beliebt; es bietet Charme vergangener Zeiten. Orte wie Komi\u017ea oder Vis vermitteln einen Hauch von Kleinstadtcharme, aber es sind Siedlungen im Landesinneren, die Ihnen wirklich ein Gef\u00fchl daf\u00fcr vermitteln, wie gro\u00dfartig diese Insel ist. Viele historische Sehensw\u00fcrdigkeiten aus vorgeschichtlicher Zeit, sch\u00f6ne K\u00fcstenorte wie Modra oder Queen's Cave sowie eine Reihe atemberaubender Inseln tragen wirklich zum ewigen Charme von Vis bei.\r\n\r\nWenn es um den <a href=\"https:\/\/www.croatia-property.net\/de\/immobilie-suchen\/?location=insel-vis-de\">Kauf einer Immobilie auf der Insel Vis geht<\/a>, reicht das Angebot von traditionellen <a href=\"https:\/\/www.croatia-property.net\/de\/immobilie-suchen\/?location=insel-vis-de&amp;type=haeuser\">Steinh\u00e4usern<\/a> (die bei Renovierung eine echte Investition darstellen) bis hin zu <a href=\"https:\/\/www.croatia-property.net\/de\/immobilie-suchen\/?location=insel-vis-de&amp;type=grundstuecke\">Grundst\u00fccken<\/a> sowohl an der K\u00fcste als auch im Landesinneren. Es werden nicht viele Wohnungen angeboten, nur weil die Bauarbeiten auf der Insel nicht sehr pr\u00e4sent sind. Vis ist in der Tat eine Wahl f\u00fcr diejenigen, die an Frieden und Gelassenheit interessiert sind. Alle diese Immobilien bieten interessante M\u00f6glichkeiten f\u00fcr das Vermietgesch\u00e4ft. Oder, wenn Sie es w\u00fcnschen, einfach f\u00fcr Ihre wundervollen Momente auf diesem Juwel einer Insel.","link":"https:\/\/www.croatia-property.net\/de\/property-city\/insel-vis-de\/","name":"Insel Vis","slug":"insel-vis-de","taxonomy":"property-city","parent":0,"meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Insel Vis - Immobilien in Kroatien<\/title>\n<meta name=\"description\" content=\"Insel Vis\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.croatia-property.net\/de\/property-city\/insel-vis-de\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Insel Vis - Immobilien in Kroatien\" \/>\n<meta property=\"og:description\" content=\"Insel Vis\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.croatia-property.net\/de\/property-city\/insel-vis-de\/\" \/>\n<meta property=\"og:site_name\" content=\"Immobilien in Kroatien\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\\\/\\\/www.croatia-property.net\\\/de\\\/property-city\\\/insel-vis-de\\\/\",\"url\":\"https:\\\/\\\/www.croatia-property.net\\\/de\\\/property-city\\\/insel-vis-de\\\/\",\"name\":\"Insel Vis - Immobilien in Kroatien\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.croatia-property.net\\\/de\\\/#website\"},\"description\":\"Insel Vis\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.croatia-property.net\\\/de\\\/property-city\\\/insel-vis-de\\\/#breadcrumb\"},\"inLanguage\":\"de\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.croatia-property.net\\\/de\\\/property-city\\\/insel-vis-de\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.croatia-property.net\\\/de\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Insel Vis\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.croatia-property.net\\\/de\\\/#website\",\"url\":\"https:\\\/\\\/www.croatia-property.net\\\/de\\\/\",\"name\":\"Immobilien in Kroatien\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.croatia-property.net\\\/de\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.croatia-property.net\\\/de\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.croatia-property.net\\\/de\\\/#organization\",\"name\":\"Croatia Property\",\"url\":\"https:\\\/\\\/www.croatia-property.net\\\/de\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/www.croatia-property.net\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.croatia-property.net\\\/wp-content\\\/uploads\\\/2017\\\/10\\\/cp-logo-bijelo.png\",\"contentUrl\":\"https:\\\/\\\/www.croatia-property.net\\\/wp-content\\\/uploads\\\/2017\\\/10\\\/cp-logo-bijelo.png\",\"width\":1916,\"height\":953,\"caption\":\"Croatia Property\"},\"image\":{\"@id\":\"https:\\\/\\\/www.croatia-property.net\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/croatia.property.net\",\"https:\\\/\\\/www.instagram.com\\\/croatiaproperty\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Insel Vis - Immobilien in Kroatien","description":"Insel Vis","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.croatia-property.net\/de\/property-city\/insel-vis-de\/","og_locale":"de_DE","og_type":"article","og_title":"Insel Vis - Immobilien in Kroatien","og_description":"Insel Vis","og_url":"https:\/\/www.croatia-property.net\/de\/property-city\/insel-vis-de\/","og_site_name":"Immobilien in Kroatien","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/www.croatia-property.net\/de\/property-city\/insel-vis-de\/","url":"https:\/\/www.croatia-property.net\/de\/property-city\/insel-vis-de\/","name":"Insel Vis - Immobilien in Kroatien","isPartOf":{"@id":"https:\/\/www.croatia-property.net\/de\/#website"},"description":"Insel Vis","breadcrumb":{"@id":"https:\/\/www.croatia-property.net\/de\/property-city\/insel-vis-de\/#breadcrumb"},"inLanguage":"de"},{"@type":"BreadcrumbList","@id":"https:\/\/www.croatia-property.net\/de\/property-city\/insel-vis-de\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.croatia-property.net\/de\/"},{"@type":"ListItem","position":2,"name":"Insel Vis"}]},{"@type":"WebSite","@id":"https:\/\/www.croatia-property.net\/de\/#website","url":"https:\/\/www.croatia-property.net\/de\/","name":"Immobilien in Kroatien","description":"","publisher":{"@id":"https:\/\/www.croatia-property.net\/de\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.croatia-property.net\/de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/www.croatia-property.net\/de\/#organization","name":"Croatia Property","url":"https:\/\/www.croatia-property.net\/de\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.croatia-property.net\/de\/#\/schema\/logo\/image\/","url":"https:\/\/www.croatia-property.net\/wp-content\/uploads\/2017\/10\/cp-logo-bijelo.png","contentUrl":"https:\/\/www.croatia-property.net\/wp-content\/uploads\/2017\/10\/cp-logo-bijelo.png","width":1916,"height":953,"caption":"Croatia Property"},"image":{"@id":"https:\/\/www.croatia-property.net\/de\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/croatia.property.net","https:\/\/www.instagram.com\/croatiaproperty"]}]}},"meta_box":{"ere_property_taxonomy_term_color":""},"_links":{"self":[{"href":"https:\/\/www.croatia-property.net\/de\/wp-json\/wp\/v2\/property-city\/188","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.croatia-property.net\/de\/wp-json\/wp\/v2\/property-city"}],"about":[{"href":"https:\/\/www.croatia-property.net\/de\/wp-json\/wp\/v2\/taxonomies\/property-city"}],"wp:post_type":[{"href":"https:\/\/www.croatia-property.net\/de\/wp-json\/wp\/v2\/property?property-city=188"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}